{"id":14821,"date":"2021-10-25T17:46:50","date_gmt":"2021-10-25T15:46:50","guid":{"rendered":"https:\/\/www.redegal.com\/politica-de-cookies\/"},"modified":"2025-05-12T09:13:57","modified_gmt":"2025-05-12T07:13:57","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/www.redegal.com\/pt-pt\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de cookies"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A REDEGAL, S.L. (doravante, Redegal) informa que o site <a href=\"https:\/\/www.redegal.com\/pt-pt\/\">https:\/\/www.redegal.com\/pt-pt\/<\/a> utiliza cookies. Abaixo, encontrar\u00e1 informa\u00e7\u00f5es detalhadas sobre as cookies utilizadas neste site, as suas caracter\u00edsticas, finalidades e a forma de as desativar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 uma Cookie?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Uma cookie \u00e9 um ficheiro que \u00e9 descarregado para o seu computador ao aceder a uma p\u00e1gina web espec\u00edfica. As cookies permitem que a p\u00e1gina web, entre outras coisas, armazene e recupere informa\u00e7\u00f5es sobre os h\u00e1bitos de navega\u00e7\u00e3o de um utilizador ou do seu dispositivo e, dependendo das informa\u00e7\u00f5es que contenham e da forma como utiliza o seu dispositivo, podem ser utilizadas para reconhecer o utilizador e melhorar o servi\u00e7o prestado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tipos de Cookies<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">https:\/\/www.redegal.com\/pt-pt\/ utiliza Cookies pr\u00f3prias e de terceiros, podendo ser cookies de sess\u00e3o ou cookies persistentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O uso das cookies permite-nos otimizar a sua navega\u00e7\u00e3o, adaptando as informa\u00e7\u00f5es e os servi\u00e7os oferecidos aos seus interesses, para proporcionar uma experi\u00eancia mais \u00e1gil e intuitiva.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cookies estritamente necess\u00e1rias<\/h2>\n\n\n\n<div class=\"table-container\">&#13;\n  <table>&#13;\n    <thead>&#13;\n      <tr>&#13;\n        <th style=\"--min-width: 110px;\"><strong>Nome<\/strong><\/th>&#13;\n        <th style=\"--min-width: 150px;\"><strong>Provedor<\/strong><\/th>&#13;\n        <th style=\"--min-width: 500px;\"><strong>Prop\u00f3sito<\/strong><\/th>&#13;\n        <th style=\"--min-width: 130px;\"><strong>Expira\u00e7\u00e3o<\/strong><\/th>&#13;\n      <\/tr>&#13;\n    <\/thead>&#13;\n    <tbody>&#13;\n      <tr>&#13;\n        <td>rc::a<\/td>&#13;\n        <td>google.com<\/td>&#13;\n        <td>Esta cookie \u00e9 utilizada para distinguir entre humanos e bots. Isso \u00e9 ben\u00e9fico para o site, permitindo gerar relat\u00f3rios v\u00e1lidos sobre o uso da p\u00e1gina.<\/td>&#13;\n        <td>Persistente<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>rc::c<\/td>&#13;\n        <td>google.com<\/td>&#13;\n        <td>Esta cookie \u00e9 utilizada para distinguir entre humanos e bots.<\/td>&#13;\n        <td>Sess\u00e3o<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>lang<\/td>&#13;\n        <td>ads.linkedin.com<\/td>&#13;\n        <td>Lembra o idioma selecionado por um utilizador para visualizar uma p\u00e1gina web.<\/td>&#13;\n        <td>Sess\u00e3o<\/td>&#13;\n      <\/tr>&#13;\n    <\/tbody>&#13;\n  <\/table>&#13;\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Cookies de terceiros <\/h2>\n\n\n\n<div class=\"table-container\">&#13;\n  <table>&#13;\n    <thead>&#13;\n      <tr>&#13;\n        <th style=\"--min-width: 200px;\"><strong>Nome<\/strong><\/th>&#13;\n        <th style=\"--min-width: 150px;\"><strong>Provedor<\/strong><\/th>&#13;\n        <th style=\"--min-width: 700px;\"><strong>Prop\u00f3sito<\/strong><\/th>&#13;\n        <th style=\"--min-width: 130px;\"><strong>Expira\u00e7\u00e3o<\/strong><\/th>&#13;\n      <\/tr>&#13;\n    <\/thead>&#13;\n    <tbody>&#13;\n      <tr>&#13;\n        <td>__hssc<\/td>&#13;\n        <td>redegal.com<\/td>&#13;\n        <td>Identifica se os dados do navegador precisam ser atualizados.<\/td>&#13;\n        <td>1 dia<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>__hssrc<\/td>&#13;\n        <td>redegal.com<\/td>&#13;\n        <td>Utilizada para reconhecer o navegador do visitante no seu retorno ao site.<\/td>&#13;\n        <td>Sess\u00e3o<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>__hstc<\/td>&#13;\n        <td>redegal.com<\/td>&#13;\n        <td>Estabelece um identificador para a sess\u00e3o. Isso permite ao site obter dados sobre o comportamento do visitante para fins estat\u00edsticos.<\/td>&#13;\n        <td>1 ano<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>AnalyticsSyncHistory<\/td>&#13;\n        <td>linkedin.com<\/td>&#13;\n        <td>Utilizada em rela\u00e7\u00e3o \u00e0 sincroniza\u00e7\u00e3o de dados com o servi\u00e7o de an\u00e1lise de terceiros.<\/td>&#13;\n        <td>29 dias<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>hubspotutk<\/td>&#13;\n        <td>redegal.com<\/td>&#13;\n        <td>Estabelece um identificador para a sess\u00e3o. Isso permite ao site obter dados sobre o comportamento do visitante para fins estat\u00edsticos.<\/td>&#13;\n        <td>1 ano<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>__ptq.gif<\/td>&#13;\n        <td>hubspot.com<\/td>&#13;\n        <td>Envia dados \u00e0 plataforma de marketing Hubspot sobre o comportamento e dispositivo do visitante. Acompanha o visitante em diferentes dispositivos e canais de marketing. <\/td>&#13;\n        <td>Sess\u00e3o<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>_fbp<\/td>&#13;\n        <td>redegal.com<\/td>&#13;\n        <td>Utilizada pelo Facebook para fornecer uma s\u00e9rie de produtos publicit\u00e1rios, como lances em tempo real de anunciantes terceiros.<\/td>&#13;\n        <td>3 meses<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>bcookie<\/td>&#13;\n        <td>linkedin.com<\/td>&#13;\n        <td>Utilizada pelo servi\u00e7o de networking social LinkedIn para rastrear o uso de servi\u00e7os incorporados.<\/td>&#13;\n        <td>2 anos<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>bscookie<\/td>&#13;\n        <td>linkedin.com<\/td>&#13;\n        <td>Utilizada pelo servi\u00e7o de networking social LinkedIn para rastrear o uso de servi\u00e7os incorporados.<\/td>&#13;\n        <td>2 anos<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>embed\/v3\/counters.gif<\/td>&#13;\n        <td>forms.hsforms.com<\/td>&#13;\n        <td>Coleta informa\u00e7\u00f5es sobre as prefer\u00eancias e\/ou intera\u00e7\u00e3o do usu\u00e1rio com conte\u00fado de campanhas web. \u00c9 utilizada na plataforma de campanha CRM, usada para propriet\u00e1rios de sites promoverem eventos ou produtos.<\/td>&#13;\n        <td>Sess\u00e3o<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>lang<\/td>&#13;\n        <td>linkedin.com<\/td>&#13;\n        <td>Estabelecida pelo LinkedIn quando uma p\u00e1gina web cont\u00e9m um painel &#8220;Siga-nos&#8221; incorporado.<\/td>&#13;\n        <td>Sess\u00e3o<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>lidc<\/td>&#13;\n        <td>linkedin.com<\/td>&#13;\n        <td>Utilizada pelo servi\u00e7o de networking social LinkedIn para rastrear o uso de servi\u00e7os incorporados.<\/td>&#13;\n        <td>1 dia<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>NID<\/td>&#13;\n        <td>google.com<\/td>&#13;\n        <td>Utilizada pelo servi\u00e7o de networking social LinkedIn para rastrear o uso de servi\u00e7os incorporados.<\/td>&#13;\n        <td>6 meses<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>tr<\/td>&#13;\n        <td>facebook.com<\/td>&#13;\n        <td>Utilizada pelo Facebook para fornecer uma s\u00e9rie de produtos publicit\u00e1rios, como lances em tempo real de anunciantes terceiros.<\/td>&#13;\n        <td>Sess\u00e3o<\/td>&#13;\n      <\/tr>&#13;\n      <tr>&#13;\n        <td>UserMatchHistory<\/td>&#13;\n        <td>linkedin.com<\/td>&#13;\n        <td>Utilizada para rastrear visitantes em v\u00e1rios sites para apresentar publicidade relevante com base nas prefer\u00eancias do visitante.<\/td>&#13;\n        <td>29 dias<\/td>&#13;\n      <\/tr>&#13;\n    <\/tbody>&#13;\n  <\/table>&#13;\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Consentimento<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ao clicar no bot\u00e3o \u201cAceitar\u201d no banner inicial de aviso, na parte inferior da p\u00e1gina, consentes a utiliza\u00e7\u00e3o das cookies n\u00e3o essenciais descritas nas condi\u00e7\u00f5es apresentadas. Al\u00e9m disso, podes personalizar esse consentimento atrav\u00e9s do bot\u00e3o \u201cOp\u00e7\u00f5es\u201d, onde encontrar\u00e1s a descri\u00e7\u00e3o e a lista detalhada de todas as cookies classificadas por categoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se n\u00e3o realizares nenhuma das a\u00e7\u00f5es anteriores, n\u00e3o ser\u00e1 entendido como consentimento para a instala\u00e7\u00e3o dessas cookies n\u00e3o essenciais e, portanto, n\u00e3o dever\u00e3o ser instaladas. No entanto, caso alguma cookie seja instalada sem o nosso conhecimento ou controlo, pedimos desculpa e solicitamos que nos informes atrav\u00e9s da sec\u00e7\u00e3o de contacto para corrigirmos a situa\u00e7\u00e3o o mais rapidamente poss\u00edvel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Configura\u00e7\u00e3o e modifica\u00e7\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Podes restringir, bloquear ou eliminar as cookies instaladas no teu dispositivo atrav\u00e9s da configura\u00e7\u00e3o das op\u00e7\u00f5es do navegador instalado no teu computador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A REDEGAL, S.L. (doravante, Redegal) informa que o site https:\/\/www.redegal.com\/pt-pt\/ utiliza cookies. Abaixo, encontrar\u00e1 informa\u00e7\u00f5es detalhadas sobre as cookies utilizadas neste site, as suas caracter\u00edsticas, finalidades e a forma de as desativar. O que \u00e9 uma Cookie? Uma cookie \u00e9 um ficheiro que \u00e9 descarregado para o seu computador ao aceder a uma p\u00e1gina web [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-14821","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Cookies | Redegal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.redegal.com\/pt-pt\/politica-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Cookies | Redegal\" \/>\n<meta property=\"og:description\" content=\"A REDEGAL, S.L. (doravante, Redegal) informa que o site https:\/\/www.redegal.com\/pt-pt\/ utiliza cookies. Abaixo, encontrar\u00e1 informa\u00e7\u00f5es detalhadas sobre as cookies utilizadas neste site, as suas caracter\u00edsticas, finalidades e a forma de as desativar. O que \u00e9 uma Cookie? Uma cookie \u00e9 um ficheiro que \u00e9 descarregado para o seu computador ao aceder a uma p\u00e1gina web [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.redegal.com\/pt-pt\/politica-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Redegal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/Redegal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-12T07:13:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.redegal.com\/wp-content\/uploads\/2021\/11\/Redegal-Social-Thumb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/politica-de-cookies\\\/\",\"url\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/politica-de-cookies\\\/\",\"name\":\"Pol\u00edtica de Cookies | Redegal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2021-10-25T15:46:50+00:00\",\"dateModified\":\"2025-05-12T07:13:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/politica-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/politica-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/politica-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/\",\"name\":\"Redegal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/#organization\",\"name\":\"Redegal\",\"url\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.redegal.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Redegal.svg\",\"contentUrl\":\"https:\\\/\\\/www.redegal.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Redegal.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Redegal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.redegal.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/Redegal\\\/\",\"https:\\\/\\\/www.instagram.com\\\/_redegal\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/redegal\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDXwbtEULPIYV2I1ugDzeUw\",\"https:\\\/\\\/x.com\\\/redegal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Cookies | Redegal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.redegal.com\/pt-pt\/politica-de-cookies\/","og_locale":"pt_PT","og_type":"article","og_title":"Pol\u00edtica de Cookies | Redegal","og_description":"A REDEGAL, S.L. (doravante, Redegal) informa que o site https:\/\/www.redegal.com\/pt-pt\/ utiliza cookies. Abaixo, encontrar\u00e1 informa\u00e7\u00f5es detalhadas sobre as cookies utilizadas neste site, as suas caracter\u00edsticas, finalidades e a forma de as desativar. O que \u00e9 uma Cookie? Uma cookie \u00e9 um ficheiro que \u00e9 descarregado para o seu computador ao aceder a uma p\u00e1gina web [&hellip;]","og_url":"https:\/\/www.redegal.com\/pt-pt\/politica-de-cookies\/","og_site_name":"Redegal","article_publisher":"https:\/\/facebook.com\/Redegal\/","article_modified_time":"2025-05-12T07:13:57+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/www.redegal.com\/wp-content\/uploads\/2021\/11\/Redegal-Social-Thumb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.redegal.com\/pt-pt\/politica-de-cookies\/","url":"https:\/\/www.redegal.com\/pt-pt\/politica-de-cookies\/","name":"Pol\u00edtica de Cookies | Redegal","isPartOf":{"@id":"https:\/\/www.redegal.com\/pt-pt\/#website"},"datePublished":"2021-10-25T15:46:50+00:00","dateModified":"2025-05-12T07:13:57+00:00","breadcrumb":{"@id":"https:\/\/www.redegal.com\/pt-pt\/politica-de-cookies\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.redegal.com\/pt-pt\/politica-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.redegal.com\/pt-pt\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.redegal.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de cookies"}]},{"@type":"WebSite","@id":"https:\/\/www.redegal.com\/pt-pt\/#website","url":"https:\/\/www.redegal.com\/pt-pt\/","name":"Redegal","description":"","publisher":{"@id":"https:\/\/www.redegal.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.redegal.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.redegal.com\/pt-pt\/#organization","name":"Redegal","url":"https:\/\/www.redegal.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.redegal.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.redegal.com\/wp-content\/uploads\/2025\/05\/Logo-Redegal.svg","contentUrl":"https:\/\/www.redegal.com\/wp-content\/uploads\/2025\/05\/Logo-Redegal.svg","width":"1024","height":"1024","caption":"Redegal"},"image":{"@id":"https:\/\/www.redegal.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/Redegal\/","https:\/\/www.instagram.com\/_redegal\/","https:\/\/www.linkedin.com\/company\/redegal\/","https:\/\/www.youtube.com\/channel\/UCDXwbtEULPIYV2I1ugDzeUw","https:\/\/x.com\/redegal"]}]}},"_links":{"self":[{"href":"https:\/\/www.redegal.com\/pt-pt\/wp-json\/wp\/v2\/pages\/14821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redegal.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.redegal.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.redegal.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redegal.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=14821"}],"version-history":[{"count":3,"href":"https:\/\/www.redegal.com\/pt-pt\/wp-json\/wp\/v2\/pages\/14821\/revisions"}],"predecessor-version":[{"id":15536,"href":"https:\/\/www.redegal.com\/pt-pt\/wp-json\/wp\/v2\/pages\/14821\/revisions\/15536"}],"wp:attachment":[{"href":"https:\/\/www.redegal.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=14821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}