{"id":8475,"date":"2021-11-18T17:52:13","date_gmt":"2021-11-18T16:52:13","guid":{"rendered":"https:\/\/redegal3.des2.net\/aviso-legal\/"},"modified":"2021-12-13T13:04:34","modified_gmt":"2021-12-13T12:04:34","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/www.redegal.com\/es-mx\/aviso-legal\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">AVISO LEGAL. EN FUNCI\u00d3N DEL RGPD &#8211; Espa\u00f1a<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El acceso a la p\u00e1gina web www.redegal.com y a la informaci\u00f3n relativa a cualesquiera de los productos y servicios contenidos en el mismo comporta la aceptaci\u00f3n de las condiciones previstas en el presente Aviso Legal. Por ello le recomendamos que lea atentamente su contenido si usted desea acceder y hacer uso de la informaci\u00f3n y los servicios ofrecidos desde la p\u00e1gina web de Redegal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redegal se constituye en el a\u00f1o 2004 con profesionales del sector TIC con amplia experiencia en el desarrollo de soluciones tecnol\u00f3gicas, capaces de satisfacer las necesidades de comunicaci\u00f3n y gesti\u00f3n de nuestros clientes. Nuestra metodolog\u00eda y experiencia, junto con equipo humano multidisciplinar, permiten poner la m\u00e1s avanzada tecnolog\u00eda al servicio de nuestros clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los datos de la empresa son: C.I.F.: B32318354, con domicilio social en R\u00faa Telleira 11 entresuelo, provincia de Ourense, e inscrita en el Registro Mercantil de Ourense y constituida ante el Notario D. Enrique Hernanz Vila en fecha 27\/02\/2004 con n\u00famero de protocolo 254.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Validez de la informaci\u00f3n<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n contenida en estas p\u00e1ginas es la vigente en la fecha de su \u00faltima actualizaci\u00f3n. Las presentes condiciones son las vigentes desde la fecha de su \u00faltima actualizaci\u00f3n. Redegal se reserva el derecho a modificarlas en cualquier momento, en cuyo caso entrar\u00e1n en vigor desde su publicaci\u00f3n y ser\u00e1n aplicables a todos los usuarios del portal desde esa fecha. Los contenidos, en especial las referencias informativas y publicitarias, salvo que expresamente se indique lo contrario, no constituyen oferta vinculante. Redegal se reserva el derecho a introducir modificaciones u omitir parcial o totalmente los actuales contenidos de la p\u00e1gina web cuando lo considere oportuno, as\u00ed como impedir o restringir el acceso de forma temporal o permanente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Pol\u00edtica de privacidad y protecci\u00f3n de datos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A los efectos de la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de datos Personales y garant\u00eda de los derechos digitales, y del Reglamento UE 2016\/679, del Parlamento Europeo y del Consejo, de 27 de abril, informamos al Usuario de que los datos de car\u00e1cter personal referentes a personas f\u00edsicas, recabados en cualquiera de la secciones de este Sitio Web, o cualesquiera otros proporcionados por el Usuario a lo largo de la relaci\u00f3n con Redegal, ser\u00e1n incluidos en ficheros de datos de car\u00e1cter personal cuyo responsable es Redegal. Las&nbsp;<strong>categor\u00edas de datos<\/strong>&nbsp;que se incluir\u00e1n en estos ficheros son datos de car\u00e1cter identificativo y datos acad\u00e9micos y profesionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las&nbsp;<strong>finalidades<\/strong>&nbsp;corresponden a la gesti\u00f3n y control de la relaci\u00f3n contractual o negocial establecida y la realizaci\u00f3n de contactos diversos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sus&nbsp;<strong>datos ser\u00e1n conservados<\/strong>&nbsp;durante el tiempo que dure la relaci\u00f3n establecida con la entidad o hasta que ejercite sus derechos de baja o supresi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redegal cumple \u00edntegramente con la legislaci\u00f3n vigente en materia de protecci\u00f3n de datos de car\u00e1cter personal, y con los compromisos de confidencialidad propios de su actividad. Por ello, el tratamiento de sus datos personales responde exclusivamente a los fines establecidos anteriormente. Estando&nbsp;<strong>legitimada<\/strong>&nbsp;por el consentimiento que expresamente se ha otorgado al aceptar estas condiciones. Redegal ha adoptado las medidas t\u00e9cnicas necesarias para mantener el nivel de seguridad requerido, seg\u00fan la naturaleza de los datos personales tratados y las circunstancias del tratamiento, con el objeto de evitar, en la medida de lo posible y siempre seg\u00fan el estado de la t\u00e9cnica, su alteraci\u00f3n, p\u00e9rdida, tratamiento o acceso no autorizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dichos datos no ser\u00e1n transferidos a terceras personas sin el correspondiente consentimiento previo, ni fuera de los casos expresamente previstos en la legislaci\u00f3n de protecci\u00f3n de datos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El Usuario garantiza que los datos e informaciones proporcionados a Redegal a trav\u00e9s del Sitio Web o por cualquier otro medio son los suyos propios y, en el caso de ceder datos de tercero, el Usuario garantiza disponer del consentimiento expreso de los titulares de<\/strong>&nbsp;los datos e informaciones para su comunicaci\u00f3n a Redegal, con el objeto de que puedan ser incorporados a nuestros ficheros en las condiciones y con las finalidades establecidas en la presente Pol\u00edtica de Privacidad. Para que la informaci\u00f3n que contienen nuestros ficheros est\u00e9 siempre actualizada y no contenga errores pedimos a nuestros clientes y usuarios que nos comuniquen, a la mayor brevedad posible, las modificaciones y rectificaciones de sus datos de car\u00e1cter personal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podr\u00e1 ejercitar&nbsp;<strong>los derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n o supresi\u00f3n, oposici\u00f3n, a la limitaci\u00f3n de su tratamiento o a la portabilidad de datos<\/strong> dirigi\u00e9ndose a Redegal, S.L. en la direcci\u00f3n postal:<br>Avenida de Santiago 9-bajo (32001 \u2013 Ourense), o a trav\u00e9s de un correo electr\u00f3nico dirigido a&nbsp;<strong><a href=\"mailto:hablamos@redegal.com\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">hablamos@redegal.com<\/a><\/strong>,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ambos casos, con la referencia: \u201cProtecci\u00f3n de Datos\u201d, a trav\u00e9s de un escrito firmado al efecto y adjuntando fotocopia de su DNI. Igualmente&nbsp;<strong>tiene usted derecho a presentar su reclamaci\u00f3n<\/strong>&nbsp;ante la Agencia de Protecci\u00f3n de Datos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, y salvo que medie autorizaci\u00f3n expresa por su parte, le comunicamos que&nbsp;<strong>NO<\/strong>&nbsp;se utilizar\u00e1n dichos datos para el env\u00edo de comunicaciones comerciales por correo electr\u00f3nico no solicitadas o no autorizadas expresa y previamente por el interesado, seg\u00fan lo estipulado en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSI).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte,&nbsp;<strong>si el usuario introduce sus datos en el formulario \u201cNewsletter\u201d, consiente expresamente que Redegal se pueda poner en contacto con usted por correo electr\u00f3nico para el env\u00edo de nuestra Newsletter con informaci\u00f3n, promociones y novedades de nuestra actividad que sean de su inter\u00e9s<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Propiedad intelectual e industrial<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La p\u00e1gina web www.redegal.com, las p\u00e1ginas que comprende y la informaci\u00f3n o elementos contenidos en las mismas, incluyen textos, documentos, fotograf\u00edas, dibujos, representaciones gr\u00e1ficas, bases de datos, programas inform\u00e1ticos, as\u00ed como logotipos, marcas, nombres comerciales, u otros signos distintivos, protegidos por derechos de propiedad intelectual o industrial, de los que Redegal son titulares o leg\u00edtimas licenciatarias.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Usos prohibidos y permitidos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Queda prohibida cualquier modalidad de explotaci\u00f3n, incluyendo todo tipo de reproducci\u00f3n, distribuci\u00f3n, cesi\u00f3n a terceros, comunicaci\u00f3n p\u00fablica y transformaci\u00f3n, mediante cualquier tipo de soporte y medio, de las obras antes referidas, creaciones y signos distintivos sin autorizaci\u00f3n previa y expresa de sus respectivos titulares. El incumplimiento de esta prohibici\u00f3n podr\u00e1 constituir infracci\u00f3n sancionable por la legislaci\u00f3n vigente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, por su cuenta y riesgo, el usuario podr\u00e1 descargar o realizar copia de tales elementos exclusivamente para su uso personal, siempre que no infrinja ninguno de los derechos de propiedad intelectual o industrial. En especial, no podr\u00e1 alterarlos, modificarlos o suprimirlos ni total ni parcialmente. En ning\u00fan caso, ello significar\u00e1 una autorizaci\u00f3n o licencia sobre los derechos de propiedad de Redegal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Responsabilidades<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Redegal no garantiza el acceso continuado, ni la correcta visualizaci\u00f3n, descarga o utilidad de los elementos e informaci\u00f3n contenidos en las p\u00e1ginas de la p\u00e1gina web, que pueden verse impedidos, dificultados o interrumpidos por factores o circunstancias fuera de su control. No es responsable de la informaci\u00f3n y dem\u00e1s contenidos integrados en espacios o p\u00e1ginas web de terceros accesibles desde la p\u00e1gina web, mediante enlaces, hiperv\u00ednculos o links, ni de la informaci\u00f3n y dem\u00e1s contenidos integrados en espacios o p\u00e1ginas web de terceros desde los que se acceda mediante enlaces, hiperv\u00ednculos o links al portal ni de la informaci\u00f3n y contenidos de cualquier p\u00e1gina web de terceros que se presente bajo la apariencia o signos distintivos salvo autorizaci\u00f3n expresa de esta \u00faltima.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Jurisdicci\u00f3n<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed mismo, y con la salvedad de lo expresado en el p\u00e1rrafo siguiente. Las partes intervinientes acuerdan que todo litigio, discrepancia, cuesti\u00f3n o reclamaci\u00f3n resultante de la ejecuci\u00f3n o interpretaci\u00f3n de las presentes condiciones o relacionado con ellas, o de otros textos que pudiera haber en el sitio web, se resolver\u00e1n definitivamente mediante sometimiento a los&nbsp;<strong>Juzgados y Tribunales de Ourense<\/strong>&nbsp;con renuncia expresa a cualquier otro fuero o demarcaci\u00f3n jurisdiccional que pudiera resultar competente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El p\u00e1rrafo anterior no ser\u00e1 de aplicaci\u00f3n en el caso de que una de las partes sea un consumidor o usuario seg\u00fan la definici\u00f3n de la normativa de protecci\u00f3n de los Consumidores y Usuarios (Real Decreto Legislativo 1\/2007, de 16 de noviembre, por el que se aprueba el texto refundido de la Ley General para la Defensa de los Consumidores y Usuarios y otras leyes complementarias), en cuyo caso, (y para un conflicto relacionado y amparado por dicha Ley). En ese caso ser\u00eda de aplicaci\u00f3n preferente el lugar designado en dicha legislaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como requisito previo al comienzo del litigio, Redegal y el Usuario se obligan a negociar de buena fe para resolver el litigio o controversia durante el plazo de un (1) mes contado desde la fecha en que una de las partes notifique por escrito a la otra su pretensi\u00f3n potencialmente litigiosa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">7. Comunicaciones<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para cualquier comunicaci\u00f3n que sea precisa entre Redegal y el Usuario, \u00e9ste deber\u00e1 dirigirse al domicilio indicado de Redegal, mediante cualquiera de los distintos medios de comunicaci\u00f3n (correo certificado o e-mail) que se indican en la secci\u00f3n CONTACTO de la Web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las comunicaciones de Redegal al Usuario se realizar\u00e1n mediante los datos aportados por \u00e9ste al registrarse en el Sitio Web o mediante los datos proporcionados en la primera comunicaci\u00f3n enviada por el Usuario.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pol\u00edtica de privacidad \u201cTrabaja con nosotros\u201d<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los datos personales, voluntariamente facilitados por usted en la cumplimentaci\u00f3n de los formularios presentes en este sitio web ser\u00e1n tratados bajo la protecci\u00f3n y las especificaciones contenidas en la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de datos Personales y garant\u00eda de los derechos digitales, y del Reglamento UE 2016\/679, del Parlamento Europeo y del Consejo, de 27 de abril, recogi\u00e9ndose en el fichero \u201cN\u00d3MINAS, PERSONAL Y RECURSOS HUMANOS\u201d, cuyo responsable es REDEGAL, S.L.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su&nbsp;<strong>finalidad<\/strong>&nbsp;corresponde a la gesti\u00f3n de n\u00f3minas y recursos humanos, incluida la gesti\u00f3n de curr\u00edculum vitae de solicitantes de empleo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las&nbsp;<strong>categor\u00edas de datos<\/strong>&nbsp;incluidos en dicho fichero, corresponder\u00e1n a datos de identificaci\u00f3n, direcciones postales o electr\u00f3nicas y datos acad\u00e9micos o profesionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>tiempo de conservaci\u00f3n<\/strong> de sus datos ser\u00e1 el correspondiente al proceso de selecci\u00f3n del personal, despu\u00e9s del cual se conservar\u00e1n por el&nbsp;<strong>plazo de un a\u00f1o<\/strong>&nbsp;de no solicitarse la supresi\u00f3n por parte del interesado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tratamiento de los datos personales llevados a cabo por Redegal responde exclusivamente a los fines establecidos anteriormente y correspondientes a los que le fueron requeridos, estando legitimada para ello por el consentimiento que expresamente se ha otorgado al aceptar las presentes condiciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dichos datos no ser\u00e1n transferidos a terceras personas sin el correspondiente consentimiento previo, ni fuera de los casos expresamente previstos en la legislaci\u00f3n de protecci\u00f3n de datos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podr\u00e1 ejercitar los&nbsp;<strong>derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n o supresi\u00f3n, oposici\u00f3n, a la limitaci\u00f3n de su tratamiento o a la portabilidad de datos<\/strong> dirigi\u00e9ndose a Redegal, S.L. en la direcci\u00f3n postal:<br>Avenida de Santiago 9-bajo (32001 \u2013 Ourense), o a trav\u00e9s de un correo electr\u00f3nico dirigido a&nbsp;<strong><a href=\"mailto:hablamos@redegal.com\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">hablamos@redegal.com<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ambos casos, con la referencia: \u201cProtecci\u00f3n de Datos\u201d, a trav\u00e9s de un escrito firmado al efecto y adjuntando fotocopia de su DNI. Igualmente&nbsp;<strong>tiene usted derecho a presentar su reclamaci\u00f3n<\/strong>&nbsp;ante la Agencia de Protecci\u00f3n de Datos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los campos marcados con \u201cRequerido\u201d son de car\u00e1cter obligatorio, por lo que la no cumplimentaci\u00f3n de dichos campos impedir\u00e1 al Usuario disfrutar, total o parcialmente, de los Servicios e informaciones ofrecidos por el Sitio Web.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pol\u00edtica de privacidad \u201cContacto o danos m\u00e1s detalles&#8221;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los datos personales, voluntariamente facilitados por usted en la cumplimentaci\u00f3n de los formularios presentes en este sitio web ser\u00e1n tratados bajo la protecci\u00f3n y las especificaciones contenidas en la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de datos Personales y garant\u00eda de los derechos digitales), y del Reglamento UE 2016\/679, del Parlamento Europeo y del Consejo, de 27 de abril, recogi\u00e9ndose en el fichero \u201cAGENDA DE CONTACTOS\u201d, cuyo responsable es REDEGAL, S.L.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>finalidad es gestionar sus consultas y env\u00edo de la informaci\u00f3n relacionada con las actividades y servicios que nos solicite.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las&nbsp;<strong>categor\u00edas de datos<\/strong> que ser\u00e1n incluidos en los ficheros pertenecientes a Redegal corresponder\u00e1n a datos de identificaci\u00f3n, direcciones postales o electr\u00f3nicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sus&nbsp;<strong>datos ser\u00e1n conservados<\/strong>&nbsp;durante el tiempo que dure la relaci\u00f3n establecida con la entidad o hasta que ejercite sus derechos de baja o supresi\u00f3n.<br>Dichos datos no ser\u00e1n transferidos a terceras personas sin el correspondiente consentimiento previo, ni fuera de los casos expresamente previstos en la legislaci\u00f3n de protecci\u00f3n de datos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podr\u00e1 ejercitar los&nbsp;<strong>derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n o supresi\u00f3n, oposici\u00f3n, a la limitaci\u00f3n de su tratamiento o a la portabilidad de datos<\/strong> dirigi\u00e9ndose a Redegal, S.L. en la direcci\u00f3n postal:<br>Avenida de Santiago 9-bajo (32001 \u2013 Ourense), o a trav\u00e9s de un correo electr\u00f3nico dirigido a&nbsp;<strong><a href=\"mailto:hablamos@redegal.com\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">hablamos@redegal.com<\/a>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ambos casos, con la referencia: \u201cProtecci\u00f3n de Datos\u201d, a trav\u00e9s de un escrito firmado al efecto y adjuntando fotocopia de su DNI. Igualmente<strong>&nbsp;tiene usted derecho a presentar su reclamaci\u00f3n&nbsp;<\/strong>ante la Agencia de Protecci\u00f3n de Datos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los campos marcados con \u201cRequerido\u201d son de car\u00e1cter obligatorio, por lo que la no cumplimentaci\u00f3n de dichos campos impedir\u00e1 al Usuario disfrutar, total o parcialmente, de los Servicios e informaciones ofrecidos por el Sitio Web.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">AVISO LEGAL &#8211; M\u00e9xico<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De conformidad con lo dispuesto en la Ley Federal de Protecci\u00f3n de Datos Personales en Posesi\u00f3n de los Particulares y su Reglamento, le informamos que sus datos personales recabados a trav\u00e9s de las solicitudes, declaraciones, avisos, y\/o dem\u00e1s manifestaciones hechas por Usted, a trav\u00e9s de medios electr\u00f3nicos, impresos o de viva voz, ser\u00e1n utilizados y resguardados \u00fanicamente por Redegal TI Mexico S.A. de C.V., en una base de datos bajo la m\u00e1s estricta confidencialidad, de conformidad a las pol\u00edticas y procedimientos de seguridad que para tal efecto implement\u00f3 Redegal TI Mexico S.A. de C.V.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los datos personales que recabamos de manera personal o directa, son entre otros, los que se describen a continuaci\u00f3n de manera enunciativa m\u00e1s no limitativa: de Identificaci\u00f3n: nombre, tel\u00e9fono, celular, correo electr\u00f3nico, Registro Federal de Contribuyentes (RFC), domicilio fiscal, fecha de nacimiento, edad, nacionalidad, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adicionalmente recolectamos datos no personalmente identificables a trav\u00e9s de cookies para mostrar publicidad de Redegal TI Mexico S.A. de C.V. a trav\u00e9s de redes de distribuci\u00f3n publicitaria de terceros. Esta informaci\u00f3n nos permite ser relevantes y mostrar publicidad a las personas que m\u00e1s desean verla.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Finalidad del tratamiento de datos personales<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El tratamiento de los datos personales proporcionados por Usted, tendr\u00e1 como finalidad \u00fanica y exclusivamente la promoci\u00f3n de todo tipo de productos ofrecidos por Redegal TI Mexico S.A. de C.V., y sus datos ser\u00e1n utilizados para informarle sobre promociones especiales, conocer su opini\u00f3n, as\u00ed como para emitir comprobantes de ingresos conforme a las disposiciones fiscales, as\u00ed como la de establecer contacto con Usted para notificarle cualquier situaci\u00f3n de inter\u00e9s sobre los productos que ofrece Redegal TI Mexico S.A. de C.V.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Revocaci\u00f3n del consentimiento del tratamiento de los datos personales<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En todo momento Usted podr\u00e1 revocar el consentimiento que ha otorgado para el tratamiento de sus datos personales con el fin de que se deje de hacer uso de los mismos; con excepci\u00f3n de los supuestos a que se refiere el art\u00edculo 26 de la Ley Federal de Protecci\u00f3n de Datos Personales en Posesi\u00f3n de los Particulares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ello, deber\u00e1 de presentar su solicitud por escrito en el domicilio ubicado en Horacio 930, Col. Polanco, Del. Miguel Hidalgo, C.P. 11560 M\u00e9xico DF, en espec\u00edfico en el \u00c1rea de Datos Personales; la cual deber\u00e1 de contener la siguiente informaci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nombre completo, domicilio y correo electr\u00f3nico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Copia de la identificaci\u00f3n del titular de los derechos, o en su caso, el documento que acredite la personalidad del representante del titular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Especificar las razones por las cuales solicita la revocaci\u00f3n del consentimiento otorgado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez presentada su solicitud, Redegal TI Mexico S.A. de C.V., dar\u00e1 respuesta a la misma dentro de un plazo m\u00e1ximo de 20 d\u00edas h\u00e1biles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Procedimiento para ejercitar el derecho de acceso, rectificaci\u00f3n, cancelaci\u00f3n u oposici\u00f3n de sus datos personales (\u201cARCO\u201d)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Usted podr\u00e1 en cualquier momento ejercer sus derechos \u201cARCO\u201d, en el domicilio ubicado en Horacio 930, Col. Polanco, Del. Miguel Hidalgo, C.P. 11560 M\u00e9xico DF, en espec\u00edfico en el \u00c1rea de Datos Personales, mediante una solicitud por escrito, la cual deber\u00e1 de contener lo siguiente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I.- Nombre completo, domicilio y correo electr\u00f3nico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">II.- Copia de la identificaci\u00f3n del titular de los derechos, o el documento que acredite la personalidad del representante legal del titular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">III.- La especificaci\u00f3n clara y precisa de los datos personales a los cuales quiere tener acceso y el derecho \u201cARCO\u201d (Acceso, Rectificaci\u00f3n, Cancelaci\u00f3n u Oposici\u00f3n) que dese\u00e9 ejercitar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">IV.- Cualquier otro elemento o documento que facilite la localizaci\u00f3n de los datos personales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">V.- En el caso de la Rectificaci\u00f3n de los datos personales, adem\u00e1s deber\u00e1 de especificar los datos que deseen ser rectificados, as\u00ed como alg\u00fan documento que justifique la rectificaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VI.- En el caso de la Oposici\u00f3n al tratamiento de los datos personales, deber\u00e1 adem\u00e1s, especificar las razones por las cuales se opone al tratamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VII.- Firma aut\u00f3grafa del interesado, o de su representante legal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ejercicio de cualquiera de los derechos \u201cARCO\u201d podr\u00e1 restringirse por las a razones se\u00f1aladas en el art\u00edculo 88 del Reglamento de la Ley Federal de Datos Personales en Posesi\u00f3n de Particulares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De conformidad con lo establecido por el art\u00edculo 34 de la Ley Federal de Protecci\u00f3n de Datos Personales en Posesi\u00f3n de los Particulares, Redegal TI Mexico S.A. de C.V. podr\u00e1 negar el acceso, rectificaci\u00f3n, cancelaci\u00f3n u oposici\u00f3n de los datos personales en los siguientes supuestos: (i) Cuando el solicitante no sea el titular de los datos personales; (ii) Cuando los datos del solicitante no se encuentren en la base de datos de Redegal TI Mexico S.A. de C.V.;(iii) Cuando se lesionen los derechos de un tercero; (iv) Cuando exista un impedimento legal o la resoluci\u00f3n de una autoridad competente; y (v) Cuando la rectificaci\u00f3n, cancelaci\u00f3n u oposici\u00f3n haya sido previamente realizada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez presentada su solicitud, Redegal TI Mexico S.A. de C.V., dar\u00e1 respuesta a la misma, dentro de un plazo m\u00e1ximo de 20 d\u00edas h\u00e1biles. Y, en caso de resultar procedente su solicitud, Redegal TI Mexico S.A. de C.V., la har\u00e1 efectiva dentro de los 15 d\u00edas siguientes a la fecha en que se comunic\u00f3 la respuesta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los plazos referidos podr\u00e1n ser ampliados una sola vez por un periodo igual siempre y cuando as\u00ed lo justifiquen las circunstancias del caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante que conserve la constancia de solicitud que haya presentado, ya que ser\u00e1 indispensable en caso de que requiera iniciar alg\u00fan procedimiento ante el Instituto Federal de Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos (IFAI).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed mismo, hacemos de su conocimiento que los plazos de conservaci\u00f3n de sus datos personales en nuestra base de datos ser\u00e1n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En caso de ser cliente de Redegal TI Mexico S.A. de C.V., la conservaci\u00f3n de los datos personales ser\u00e1 por un per\u00edodo m\u00ednimo de 10 a\u00f1os, salvo que la relaci\u00f3n contractual exceda de dicho plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En caso de no ser cliente de Redegal TI Mexico S.A. de C.V., la conservaci\u00f3n de los datos personales ser\u00e1 por un per\u00edodo m\u00e1ximo de 1 a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez transcurridos estos plazos, y en caso de que se haya cumplido la finalidad del tratamiento de los datos personales, se proceder\u00e1 a la destrucci\u00f3n de los mismos, para su posterior supresi\u00f3n de la base de datos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Transferencia de datos personales<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sus datos personales podr\u00e1n ser transferidos y tratados dentro o fuera del pa\u00eds, a personas distintas a Redegal TI Mexico S.A. de C.V., Por lo que su informaci\u00f3n podr\u00e1 ser compartida con Prestadores de Servicios Externos que manejen o administren las bases de datos en las cuales se almacenar\u00e1 dicha informaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el entendido de que sus datos personales podr\u00e1n ser utilizados por Redegal TI Mexico S.A. de C.V. para fines mercadol\u00f3gicos, de publicidad, pero no podr\u00e1n ser proporcionados a terceros ajenos a Redegal TI Mexico S.A. de C.V., para dichos fines.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si Usted no manifiesta su oposici\u00f3n para que sus datos personales sean transferidos, se entender\u00e1 que ha otorgado su consentimiento para ello.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Manifiesta el titular<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Que por virtud de lo anterior, con la firma del presente aviso, consiente de manera irrevocable y autorizo a Redegal TI Mexico S.A. de C.V., para que mis datos personales sean transferidos, usados y conservados en los t\u00e9rminos antes descritos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Modificaciones al aviso de privacidad<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Redegal TI Mexico S.A. de C.V., se reserva el derecho de modificar en cualquier momento el presente Aviso de Privacidad, mismo que le ser\u00e1 dado a conocer a trav\u00e9s del estado de su ejecutivo y\/o cuenta y\/o a trav\u00e9s de un aviso en el sitio web<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez puesto a su disposici\u00f3n, y en caso de no manifestar su oposici\u00f3n al mismo, se entender\u00e1 que consiente t\u00e1citamente el tratamiento de sus datos, en los t\u00e9rminos aqu\u00ed contenidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AVISO LEGAL. EN FUNCI\u00d3N DEL RGPD &#8211; Espa\u00f1a El acceso a la p\u00e1gina web www.redegal.com y a la informaci\u00f3n relativa a cualesquiera de los productos y servicios contenidos en el mismo comporta la aceptaci\u00f3n de las condiciones previstas en el presente Aviso Legal. Por ello le recomendamos que lea atentamente su contenido si usted desea [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-8475","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso legal - Redegal<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso legal - Redegal\" \/>\n<meta property=\"og:description\" content=\"AVISO LEGAL. EN FUNCI\u00d3N DEL RGPD &#8211; Espa\u00f1a El acceso a la p\u00e1gina web www.redegal.com y a la informaci\u00f3n relativa a cualesquiera de los productos y servicios contenidos en el mismo comporta la aceptaci\u00f3n de las condiciones previstas en el presente Aviso Legal. Por ello le recomendamos que lea atentamente su contenido si usted desea [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.redegal.com\/es-mx\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Redegal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/Redegal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-13T12:04:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.redegal.com\/wp-content\/uploads\/2021\/11\/Redegal-Social-Thumb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/aviso-legal\\\/\",\"url\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/aviso-legal\\\/\",\"name\":\"Aviso legal - Redegal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/#website\"},\"datePublished\":\"2021-11-18T16:52:13+00:00\",\"dateModified\":\"2021-12-13T12:04:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/aviso-legal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/aviso-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/aviso-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/#website\",\"url\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/\",\"name\":\"Redegal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/#organization\",\"name\":\"Redegal\",\"url\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.redegal.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Redegal.svg\",\"contentUrl\":\"https:\\\/\\\/www.redegal.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Logo-Redegal.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Redegal\"},\"image\":{\"@id\":\"https:\\\/\\\/www.redegal.com\\\/es-mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/Redegal\\\/\",\"https:\\\/\\\/www.instagram.com\\\/_redegal\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/redegal\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDXwbtEULPIYV2I1ugDzeUw\",\"https:\\\/\\\/x.com\\\/redegal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso legal - Redegal","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_MX","og_type":"article","og_title":"Aviso legal - Redegal","og_description":"AVISO LEGAL. EN FUNCI\u00d3N DEL RGPD &#8211; Espa\u00f1a El acceso a la p\u00e1gina web www.redegal.com y a la informaci\u00f3n relativa a cualesquiera de los productos y servicios contenidos en el mismo comporta la aceptaci\u00f3n de las condiciones previstas en el presente Aviso Legal. Por ello le recomendamos que lea atentamente su contenido si usted desea [&hellip;]","og_url":"https:\/\/www.redegal.com\/es-mx\/aviso-legal\/","og_site_name":"Redegal","article_publisher":"https:\/\/facebook.com\/Redegal\/","article_modified_time":"2021-12-13T12:04:34+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/www.redegal.com\/wp-content\/uploads\/2021\/11\/Redegal-Social-Thumb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"19 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.redegal.com\/es-mx\/aviso-legal\/","url":"https:\/\/www.redegal.com\/es-mx\/aviso-legal\/","name":"Aviso legal - Redegal","isPartOf":{"@id":"https:\/\/www.redegal.com\/es-mx\/#website"},"datePublished":"2021-11-18T16:52:13+00:00","dateModified":"2021-12-13T12:04:34+00:00","breadcrumb":{"@id":"https:\/\/www.redegal.com\/es-mx\/aviso-legal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.redegal.com\/es-mx\/aviso-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.redegal.com\/es-mx\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.redegal.com\/es-mx\/"},{"@type":"ListItem","position":2,"name":"Aviso legal"}]},{"@type":"WebSite","@id":"https:\/\/www.redegal.com\/es-mx\/#website","url":"https:\/\/www.redegal.com\/es-mx\/","name":"Redegal","description":"","publisher":{"@id":"https:\/\/www.redegal.com\/es-mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.redegal.com\/es-mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.redegal.com\/es-mx\/#organization","name":"Redegal","url":"https:\/\/www.redegal.com\/es-mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.redegal.com\/es-mx\/#\/schema\/logo\/image\/","url":"https:\/\/www.redegal.com\/wp-content\/uploads\/2025\/05\/Logo-Redegal.svg","contentUrl":"https:\/\/www.redegal.com\/wp-content\/uploads\/2025\/05\/Logo-Redegal.svg","width":"1024","height":"1024","caption":"Redegal"},"image":{"@id":"https:\/\/www.redegal.com\/es-mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/Redegal\/","https:\/\/www.instagram.com\/_redegal\/","https:\/\/www.linkedin.com\/company\/redegal\/","https:\/\/www.youtube.com\/channel\/UCDXwbtEULPIYV2I1ugDzeUw","https:\/\/x.com\/redegal"]}]}},"_links":{"self":[{"href":"https:\/\/www.redegal.com\/es-mx\/wp-json\/wp\/v2\/pages\/8475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redegal.com\/es-mx\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.redegal.com\/es-mx\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.redegal.com\/es-mx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redegal.com\/es-mx\/wp-json\/wp\/v2\/comments?post=8475"}],"version-history":[{"count":0,"href":"https:\/\/www.redegal.com\/es-mx\/wp-json\/wp\/v2\/pages\/8475\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redegal.com\/es-mx\/wp-json\/wp\/v2\/media?parent=8475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}